{"id":914,"count":1,"description":"","link":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/","name":"cognizant placement","slug":"cognizant-placement","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.13 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>cognizant placement Archives - Shoolini University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cognizant placement Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/\" \/>\n<meta property=\"og:site_name\" content=\"Shoolini University\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@shooliniuniv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/tag\\\/cognizant-placement\\\/\",\"url\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/tag\\\/cognizant-placement\\\/\",\"name\":\"cognizant placement Archives - Shoolini University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/tag\\\/cognizant-placement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/tag\\\/cognizant-placement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cognizant placement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/\",\"name\":\"Shoolini University\",\"description\":\"Best University in North India\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shooliniuniversity.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"cognizant placement Archives - Shoolini University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/","og_locale":"en_US","og_type":"article","og_title":"cognizant placement Archives","og_url":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/","og_site_name":"Shoolini University","twitter_card":"summary_large_image","twitter_site":"@shooliniuniv","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/","url":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/","name":"cognizant placement Archives - Shoolini University","isPartOf":{"@id":"https:\/\/shooliniuniversity.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/shooliniuniversity.com\/blog\/tag\/cognizant-placement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shooliniuniversity.com\/blog\/"},{"@type":"ListItem","position":2,"name":"cognizant placement"}]},{"@type":"WebSite","@id":"https:\/\/shooliniuniversity.com\/blog\/#website","url":"https:\/\/shooliniuniversity.com\/blog\/","name":"Shoolini University","description":"Best University in North India","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shooliniuniversity.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/shooliniuniversity.com\/blog\/wp-json\/wp\/v2\/tags\/914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shooliniuniversity.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/shooliniuniversity.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/shooliniuniversity.com\/blog\/wp-json\/wp\/v2\/posts?tags=914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}